{"id":10840,"date":"2017-06-11T10:00:38","date_gmt":"2017-06-11T08:00:38","guid":{"rendered":"https:\/\/www.motoblouz.com\/enjoytheride\/enjoytheride\/?p=10840"},"modified":"2023-09-20T16:37:30","modified_gmt":"2023-09-20T14:37:30","slug":"video-blouson-vquattro-ve51","status":"publish","type":"post","link":"https:\/\/www.motoblouz.com\/enjoytheride\/equipement-motard\/10840-video-blouson-vquattro-ve51-2017-06-11","title":{"rendered":"VIDEO : Blouson V&rsquo;Quattro VE51"},"content":{"rendered":"<p><a href=\"https:\/\/www.motoblouz.com\/marque\/v-quattro.html#utm_source=Video_Produit&amp;utm_medium=EnjoyTheRide&amp;utm_campaign=AutoPromotion\" target=\"_blank\" rel=\"noopener\">V&rsquo;Quattro<\/a>\u00a0est une marque d\u00e9velopp\u00e9e sous le soleil d&rsquo;Aix-en-Provence, dans le Sud de la France. Alors quand il est question de cr\u00e9er un\u00a0<a href=\"https:\/\/www.motoblouz.com\/achat-equipement-motard-blouson-moto-textile-12004.html#utm_source=Video_Produit&amp;utm_medium=EnjoyTheRide&amp;utm_campaign=AutoPromotion\" target=\"_blank\" rel=\"noopener\">blouson moto<\/a> pour l&rsquo;\u00e9t\u00e9, les gars savent de quoi ils parlent ! Le <strong>blouson V&rsquo;Quattro VE51<\/strong> fait partie de leurs nouveaut\u00e9s 2017. Un blouson estival, oui mais polyvalent. Il saura vous rafra\u00eechir en cas de fortes chaleurs, et vous aider \u00e0 affronter vents (et mar\u00e9es). Vous \u00eates \u00e0 la recherche d&rsquo;un blouson ventil\u00e9 ? On vous le dit, celui-ci a bien plus d&rsquo;un tour dans ses poches.<\/p>\n<p><!--more--><\/p>\n<h2>Passez l&rsquo;\u00e9t\u00e9 au frais avec le blouson V&rsquo;Quattro VE51<\/h2>\n<p>La moto, c&rsquo;est le r\u00eave\u00a0quand il fait chaud. Mais quand il fait\u00a0TROP chaud, le r\u00eave peut vite se transformer en cauchemar&#8230; Enfin, si on n&rsquo;est pas bien \u00e9quip\u00e9 bien s\u00fbr. L\u00e0, on est sur un <strong>blouson ventil\u00e9\u00a0<\/strong>sp\u00e9cialement pens\u00e9 pour la saison estivale. Con\u00e7u dans du\u00a0polyester 700 deniers, il s&rsquo;av\u00e8re hyper r\u00e9sistant \u00e0 l&rsquo;abrasion, et \u00e0 la\u00a0chaleur. Cela dit, la fra\u00eecheur, on la doit surtout aux <strong>grosses pi\u00e8ces en maille mesh<\/strong> ventil\u00e9es au niveau du buste, des bras et du dos.\u00a0Mais comme on vous le disait, le blouson V&rsquo;Quattro VE51 est polyvalent ! Gr\u00e2ce \u00e0 une\u00a0<strong>doublure amovible <em>Windbreaker <\/em><\/strong>(coupe-vent <em>in french<\/em>) et \u00e9tanche,\u00a0vous pouvez le sortir \u00e0 d&rsquo;autres moments qu&rsquo;en plein mois d&rsquo;ao\u00fbt, entre 10h et 18h.<\/p>\n<p>Vu qu&rsquo;on est sur un blouson textile, il s&rsquo;av\u00e8re plut\u00f4t souple, confortable. En plus, histoire de vous mettre bien \u00e0 l&rsquo;aise, il dispose de <strong>soufflets d&rsquo;aisance<\/strong> derri\u00e8re les coudes et les \u00e9paules. Le genre d&rsquo;\u00e9quipement qu&rsquo;on a l&rsquo;habitude de voir sur des blousons racing.<\/p>\n<p>On termine avec un\u00a0focus sur la s\u00e9curit\u00e9 : il ne faut pas oublier qu&rsquo;on reste sur un <a href=\"https:\/\/www.motoblouz.com\/enjoytheride\/guide-achat\/blouson-moto\/les-aspects-pratiques\" target=\"_blank\" rel=\"noopener\">blouson de moto<\/a>. Il dispose des traditionnelles <strong>coques de renfort,<\/strong> <strong>homologu\u00e9es CE<\/strong>, aux \u00e9paules et aux coudes. Pas de <a href=\"https:\/\/www.motoblouz.com\/achat-equipement-motard-dorsale-et-protection-securite-5710.html#utm_source=Video_Produit&amp;utm_medium=EnjoyTheRide&amp;utm_campaign=AutoPromotion\" target=\"_blank\" rel=\"noopener\">dorsale<\/a> de s\u00e9rie, malheureusement, mais une poche vous permet de l&rsquo;ajouter. Enfin, on peut aussi noter les<strong> inserts r\u00e9fl\u00e9chissants<\/strong> qui offrent une meilleure visibilit\u00e9. Question visibilit\u00e9, et esth\u00e9tique, le <strong>blouson V&rsquo;Quattro VE51<\/strong> est du genre plut\u00f4t sobre, ici en\u00a0noir classique. Mais sachez qu&rsquo;il est aussi dispo dans une large gamme de coloris&#8230; pour s&rsquo;adapter \u00e0 toutes les garde-robes. Polyvalent, jusque dans le style.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V&rsquo;Quattro\u00a0est une marque d\u00e9velopp\u00e9e sous le soleil d&rsquo;Aix-en-Provence, dans le Sud de la France. Alors quand il est question de cr\u00e9er un\u00a0blouson moto pour l&rsquo;\u00e9t\u00e9, les gars savent de quoi ils parlent ! Le blouson V&rsquo;Quattro VE51 fait partie de leurs nouveaut\u00e9s 2017. Un blouson estival, oui mais polyvalent. Il saura vous rafra\u00eechir en cas [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":10841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"inline_featured_image":false,"footnotes":""},"categories":[6,5,307],"tags":[321,371,196],"yoast":{"focuskw":"blouson V'Quattro VE51","title":"Blouson V'Quattro VE51, la vid\u00e9o de pr\u00e9sentation sur Motoblouz","metadesc":"Bruno vous pr\u00e9sente le blouson V'Quattro VE51: un blouson moto ventil\u00e9, polyvalent et bien pens\u00e9, pour passer l'\u00e9t\u00e9 sur la route. D\u00e9couvrez-le en vid\u00e9o !","linkdex":"94","metakeywords":"","meta-robots-noindex":"","meta-robots-nofollow":"","meta-robots-adv":"","canonical":"","redirect":"","opengraph-title":"","opengraph-description":"","opengraph-image":"","twitter-title":"","twitter-description":"","twitter-image":""},"bk_author_score":["0"],"bk_final_score":[],"bk_summary":[],"bk_cs1":["0"],"bk_cs2":["0"],"bk_cs3":["0"],"bk_cs4":["0"],"bk_cs5":["0"],"bk_cs6":["0"],"bk_ct1":[],"bk_ct2":[],"bk_ct3":[],"bk_ct4":[],"bk_ct5":[],"bk_ct6":[],"bk_gallery_content":[],"bk_image_upload":[],"bk_media_embed_code_post":["https:\/\/www.youtube.com\/watch?v=Nu_fp0qx87E"],"bk_page_fullwidth_checkbox":[],"bk_post_fullwidth_checkbox":["0"],"bk_review_checkbox":["0"],"lswd-posts-on-top":"false","_d3t_product_info_activate":["1"],"_d3t_product_info_reference":["VQ0256"],"_d3t_product_media_detoure":["https:\/\/www.motoblouz.com\/enjoytheride\/wp-content\/uploads\/2017\/08\/Blouson-moto-Vquatro.png"],"d3t_etc_reference":["FRV10840"],"d3t_etc_translate_yoast_focuskw":[],"d3t_etc_translate_yoast_title":[],"d3t_etc_translate_yoast_metadesc":[],"d3t_etc_translate_product_media_detoure":[],"d3t_etc_translate_product_info_reference":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/posts\/10840"}],"collection":[{"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/comments?post=10840"}],"version-history":[{"count":0,"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/posts\/10840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/media\/10841"}],"wp:attachment":[{"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/media?parent=10840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/categories?post=10840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.motoblouz.com\/enjoytheride\/wp-json\/wp\/v2\/tags?post=10840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}